{"id":25630,"date":"2021-01-26T10:16:25","date_gmt":"2021-01-26T09:16:25","guid":{"rendered":"https:\/\/www.elbosquegolf.com\/?p=25630"},"modified":"2021-01-26T10:16:27","modified_gmt":"2021-01-26T09:16:27","slug":"arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo","status":"publish","type":"post","link":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/","title":{"rendered":"Arrancamos la fase final de las obras de reforma del campo"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><strong>En esta fase final se acometer\u00e1 la mejora de los 9 primeros hoyos del recorrido que quedan por remodelar<\/strong><\/h4>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>La reforma durar\u00e1 hasta octubre y consolidar\u00e1 el campo como uno de los mejores de Espa\u00f1a<\/strong><\/h4>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Cerraremos 2021 con una inversi\u00f3n de 3 millones de euros y habiendo renovado los 18 hoyos con un nuevo c\u00e9sped de alta resistencia, ganando calidad y reduciendo el consumo de agua y productos fitosanitarios<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">El Club de Golf El Bosque ha comenzado la \u00faltima fase de su reforma con la que finalizar\u00e1 un ambicioso proyecto de renovaci\u00f3n de su recorrido. Dicho proyecto supone una inversi\u00f3n que rondar\u00e1 los 2,8 millones de euros y que se ha ejecutado en tres fases. Una primera, realizada en 2019 y que incluy\u00f3 la construcci\u00f3n de una zona nueva de juego corto y un puttingreen; una segunda, que se inaugur\u00f3 el pasado octubre y que afect\u00f3 a los 9 segundos hoyos; y una tercera, que se inicia ahora y en la que se reformar\u00e1n los 9 primeros. La fecha prevista para su inauguraci\u00f3n es principios de octubre de este mismo a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los objetivos de esta\nreforma son principalmente el de dar un salto de calidad en el mantenimiento\ndel recorrido, al mismo tiempo que\nhacerlo m\u00e1s sostenible y ecol\u00f3gico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ejecuci\u00f3n de\nesta \u00faltima fase es muy similar a la del a\u00f1o pasado. Adem\u00e1s de la sustituci\u00f3n\nde todo el sistema de riego, con el que se mejorar\u00e1 la uniformidad en la\ncobertura del c\u00e9sped y se reducir\u00e1 el consumo de agua, se instalar\u00e1 tambi\u00e9n una\nnueva red de drenajes y se mejorar\u00e1 el perfil del suelo, permitiendo de esta\nforma tener una superficie firme \u00f3ptima para el juego. Asimismo, se reformar\u00e1n\ntodos los bunkers, empleando el novedoso y puntero m\u00e9todo constructivo Better\nBilly Bunker.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00fanico cambio sustancial con respecto\na la fase anterior es el remplazo de cubierta vegetal de los greenes,\nsustituyendo el antiguo c\u00e9sped por uno menos proclive a enfermedades y que, por\ntanto, permite reducir de manera sustancial el uso de productos fitosanitarios\npara su cuidado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el punto de vista\necol\u00f3gico, el proyecto recoge tres factores clave encaminados a la reducci\u00f3n del consumo h\u00eddrico. El primero es un sistema de riego mucho m\u00e1s moderno\ny automatizado, con aspersores m\u00e1s eficientes y una\nred hidr\u00e1ulica totalmente renovada. El segundo es la elecci\u00f3n de las variedades\ndel c\u00e9sped a plantar, siendo la bermuda 419 la opci\u00f3n elegida para las calles y\nla Tahoma en tees; y el tercero es la reducci\u00f3n de zonas de riego que, por su\nlocalizaci\u00f3n, no tienen incidencia en el juego. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto es obra de la\ningenier\u00eda Acttua Golf Services y la construcci\u00f3n la est\u00e1 llevando a cabo\nGarden&amp;Golf, dos empresas l\u00edderes en\nel sector y que han intervenido en los \u00faltimos grandes proyectos de renovaci\u00f3n\nque se han realizado en Espa\u00f1a.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta fase final se acometer\u00e1 la mejora de los 9 primeros hoyos del recorrido que quedan por remodelar La reforma durar\u00e1 hasta octubre y consolidar\u00e1 el campo como uno de los mejores de Espa\u00f1a Cerraremos 2021 con una inversi\u00f3n de 3 millones de euros y habiendo renovado los 18 hoyos con un nuevo c\u00e9sped de alta resistencia, ganando calidad<\/p>\n<div class=\"h10\"><\/div>\n<p><a class=\"more-link2 flat\" href=\"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":25631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[78,26,29,30,79],"class_list":["post-25630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporativo","tag-campo","tag-golf","tag-obras","tag-reforma","tag-renovacion"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La reforma durar\u00e1 hasta octubre y consolidar\u00e1 el campo como uno de los mejores de Espa\u00f1a.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"elbosquec\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El bosque golf | Club de Golf Valencia\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Arrancamos la fase final de las obras de reforma del campo | El bosque golf\" \/>\n\t\t<meta property=\"og:description\" content=\"La reforma durar\u00e1 hasta octubre y consolidar\u00e1 el campo como uno de los mejores de Espa\u00f1a.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-01-26T09:16:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-01-26T09:16:27+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Arrancamos la fase final de las obras de reforma del campo | El bosque golf\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La reforma durar\u00e1 hasta octubre y consolidar\u00e1 el campo como uno de los mejores de Espa\u00f1a.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\\\/#article\",\"name\":\"Arrancamos la fase final de las obras de reforma del campo | El bosque golf\",\"headline\":\"Arrancamos la fase final de las obras de reforma del campo\",\"author\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/author\\\/elbosquec\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elbosquegolf.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/El-Bosque-obras.jpg\",\"width\":1913,\"height\":1076},\"datePublished\":\"2021-01-26T10:16:25+01:00\",\"dateModified\":\"2021-01-26T10:16:27+01:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\\\/#webpage\"},\"articleSection\":\"Corporativo, campo, golf, obras, reforma, renovaci\\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en#listItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/category\\\/corporativo\\\/#listItem\",\"name\":\"Corporativo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/category\\\/corporativo\\\/#listItem\",\"position\":2,\"name\":\"Corporativo\",\"item\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/category\\\/corporativo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\\\/#listItem\",\"name\":\"Arrancamos la fase final de las obras de reforma del campo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en#listItem\",\"name\":\"Hogar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\\\/#listItem\",\"position\":3,\"name\":\"Arrancamos la fase final de las obras de reforma del campo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/category\\\/corporativo\\\/#listItem\",\"name\":\"Corporativo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/#organization\",\"name\":\"El bosque golf\",\"description\":\"Club de Golf Valencia\",\"url\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/author\\\/elbosquec\\\/#author\",\"url\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/author\\\/elbosquec\\\/\",\"name\":\"elbosquec\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\\\/#webpage\",\"url\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\\\/\",\"name\":\"Arrancamos la fase final de las obras de reforma del campo | El bosque golf\",\"description\":\"La reforma durar\\u00e1 hasta octubre y consolidar\\u00e1 el campo como uno de los mejores de Espa\\u00f1a.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/author\\\/elbosquec\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/author\\\/elbosquec\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elbosquegolf.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/El-Bosque-obras.jpg\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\\\/#mainImage\",\"width\":1913,\"height\":1076},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\\\/#mainImage\"},\"datePublished\":\"2021-01-26T10:16:25+01:00\",\"dateModified\":\"2021-01-26T10:16:27+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/\",\"name\":\"El bosque\",\"description\":\"Club de Golf Valencia\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Arrancamos la fase final de las obras de reforma del campo | El bosque golf","description":"La reforma durar\u00e1 hasta octubre y consolidar\u00e1 el campo como uno de los mejores de Espa\u00f1a.","canonical_url":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/#article","name":"Arrancamos la fase final de las obras de reforma del campo | El bosque golf","headline":"Arrancamos la fase final de las obras de reforma del campo","author":{"@id":"https:\/\/www.elbosquegolf.com\/en\/author\/elbosquec\/#author"},"publisher":{"@id":"https:\/\/www.elbosquegolf.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.elbosquegolf.com\/wp-content\/uploads\/2021\/01\/El-Bosque-obras.jpg","width":1913,"height":1076},"datePublished":"2021-01-26T10:16:25+01:00","dateModified":"2021-01-26T10:16:27+01:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/#webpage"},"isPartOf":{"@id":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/#webpage"},"articleSection":"Corporativo, campo, golf, obras, reforma, renovaci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en#listItem","position":1,"name":"Hogar","item":"https:\/\/www.elbosquegolf.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en\/category\/corporativo\/#listItem","name":"Corporativo"}},{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en\/category\/corporativo\/#listItem","position":2,"name":"Corporativo","item":"https:\/\/www.elbosquegolf.com\/en\/category\/corporativo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/#listItem","name":"Arrancamos la fase final de las obras de reforma del campo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en#listItem","name":"Hogar"}},{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/#listItem","position":3,"name":"Arrancamos la fase final de las obras de reforma del campo","previousItem":{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en\/category\/corporativo\/#listItem","name":"Corporativo"}}]},{"@type":"Organization","@id":"https:\/\/www.elbosquegolf.com\/en\/#organization","name":"El bosque golf","description":"Club de Golf Valencia","url":"https:\/\/www.elbosquegolf.com\/en\/"},{"@type":"Person","@id":"https:\/\/www.elbosquegolf.com\/en\/author\/elbosquec\/#author","url":"https:\/\/www.elbosquegolf.com\/en\/author\/elbosquec\/","name":"elbosquec"},{"@type":"WebPage","@id":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/#webpage","url":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/","name":"Arrancamos la fase final de las obras de reforma del campo | El bosque golf","description":"La reforma durar\u00e1 hasta octubre y consolidar\u00e1 el campo como uno de los mejores de Espa\u00f1a.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.elbosquegolf.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/#breadcrumblist"},"author":{"@id":"https:\/\/www.elbosquegolf.com\/en\/author\/elbosquec\/#author"},"creator":{"@id":"https:\/\/www.elbosquegolf.com\/en\/author\/elbosquec\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.elbosquegolf.com\/wp-content\/uploads\/2021\/01\/El-Bosque-obras.jpg","@id":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/#mainImage","width":1913,"height":1076},"primaryImageOfPage":{"@id":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/#mainImage"},"datePublished":"2021-01-26T10:16:25+01:00","dateModified":"2021-01-26T10:16:27+01:00"},{"@type":"WebSite","@id":"https:\/\/www.elbosquegolf.com\/en\/#website","url":"https:\/\/www.elbosquegolf.com\/en\/","name":"El bosque","description":"Club de Golf Valencia","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.elbosquegolf.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"El bosque golf | Club de Golf Valencia","og:type":"article","og:title":"Arrancamos la fase final de las obras de reforma del campo | El bosque golf","og:description":"La reforma durar\u00e1 hasta octubre y consolidar\u00e1 el campo como uno de los mejores de Espa\u00f1a.","og:url":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/","article:published_time":"2021-01-26T09:16:25+00:00","article:modified_time":"2021-01-26T09:16:27+00:00","twitter:card":"summary_large_image","twitter:title":"Arrancamos la fase final de las obras de reforma del campo | El bosque golf","twitter:description":"La reforma durar\u00e1 hasta octubre y consolidar\u00e1 el campo como uno de los mejores de Espa\u00f1a."},"aioseo_meta_data":{"post_id":"25630","title":"Arrancamos la fase final de las obras de reforma del campo | #site_title","description":"La reforma durar\u00e1 hasta octubre y consolidar\u00e1 el campo como uno de los mejores de Espa\u00f1a.","keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-12-23 18:27:57","updated":"2026-08-24 20:08:30","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elbosquegolf.com\/en\" title=\"Hogar\">Hogar<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elbosquegolf.com\/en\/category\/corporativo\/\" title=\"Corporativo\">Corporativo<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tArrancamos la fase final de las obras de reforma del campo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Hogar","link":"https:\/\/www.elbosquegolf.com\/en"},{"label":"Corporativo","link":"https:\/\/www.elbosquegolf.com\/en\/category\/corporativo\/"},{"label":"Arrancamos la fase final de las obras de reforma del campo","link":"https:\/\/www.elbosquegolf.com\/en\/arrancamos-la-fase-final-de-las-obras-de-reforma-del-campo\/"}],"_links":{"self":[{"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/posts\/25630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/comments?post=25630"}],"version-history":[{"count":0,"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/posts\/25630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/media\/25631"}],"wp:attachment":[{"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/media?parent=25630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/categories?post=25630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/tags?post=25630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}