{"id":25568,"date":"2020-10-26T16:26:24","date_gmt":"2020-10-26T15:26:24","guid":{"rendered":"https:\/\/www.elbosquegolf.com\/?p=25568"},"modified":"2020-10-26T16:26:26","modified_gmt":"2020-10-26T15:26:26","slug":"nuevos-horarios-del-club","status":"publish","type":"post","link":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/","title":{"rendered":"Nuevos horarios del Club"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La pasada madrugada del s\u00e1bado al domingo, 24-25 de octubre, retrasamos los relojes una hora. Esta acci\u00f3n tambi\u00e9n ha tenido consecuencias en los horarios de nuestros servicios que pasamos a detallarte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el cambio de hora, hemos adaptado los horarios de apertura y cierre de las diferentes \u00e1reas y servicios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TIENDA:<br>&#8211; Lunes a viernes de 8 a 18 horas<br>&#8211; S\u00e1bados y festivos de 7:30 a 18 horas<br>&#8211; Domingos de 7:30 a 17:30 horas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CUARTO DE PALOS:<br>&#8211; Lunes a viernes de 8 a 19 horas<br>&#8211; S\u00e1bados y festivos de 7:30 a 19 horas<br>&#8211; Domingos de 7:30 a 18:30 horas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CASA CLUB Y CAFETERIA:<br>&#8211; Lunes a viernes de 8 a 19 horas<br>&#8211; S\u00e1bados y festivos de 7:30 a 19 horas<br>&#8211; Domingos de 7:30 a 18:30 horas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, el horario de iluminaci\u00f3n de la cancha de pr\u00e1cticas ser\u00e1&nbsp;parcial (s\u00f3lo parte de abajo): lunes, martes y domingos de 18 a 19 horas. Y total: mi\u00e9rcoles, jueves, viernes y s\u00e1bado en ese mismo horario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para cualquier sugerencia o comentario sobre los nuevos horarios, puedes escribirnos a&nbsp;<a href=\"mailto:golf.office@elbosquegolf.com\">golf.office@elbosquegolf.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pasada madrugada del s\u00e1bado al domingo, 24-25 de octubre, retrasamos los relojes una hora. Esta acci\u00f3n tambi\u00e9n ha tenido consecuencias en los horarios de nuestros servicios que pasamos a detallarte. Con el cambio de hora, hemos adaptado los horarios de apertura y cierre de las diferentes \u00e1reas y servicios. TIENDA:&#8211; Lunes a viernes de 8 a 18 horas&#8211; S\u00e1bados<\/p>\n<div class=\"h10\"><\/div>\n<p><a class=\"more-link2 flat\" href=\"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":25569,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[71,70],"class_list":["post-25568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporativo","tag-club","tag-horarios"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Con el cambio de hora, hemos adaptado los horarios de apertura y cierre de las diferentes \u00e1reas y servicios.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"elbosquec\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El bosque golf | Club de Golf Valencia\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Nuevos horarios del Club | El bosque golf\" \/>\n\t\t<meta property=\"og:description\" content=\"Con el cambio de hora, hemos adaptado los horarios de apertura y cierre de las diferentes \u00e1reas y servicios.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-10-26T15:26:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-10-26T15:26:26+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Nuevos horarios del Club | El bosque golf\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Con el cambio de hora, hemos adaptado los horarios de apertura y cierre de las diferentes \u00e1reas y servicios.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/nuevos-horarios-del-club\\\/#article\",\"name\":\"Nuevos horarios del Club | El bosque golf\",\"headline\":\"Nuevos horarios del Club\",\"author\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/author\\\/elbosquec\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elbosquegolf.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Nuevo-horario-copia.jpg\",\"width\":1080,\"height\":1080},\"datePublished\":\"2020-10-26T16:26:24+01:00\",\"dateModified\":\"2020-10-26T16:26:26+01:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/nuevos-horarios-del-club\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/nuevos-horarios-del-club\\\/#webpage\"},\"articleSection\":\"Corporativo, club, horarios\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/nuevos-horarios-del-club\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en#listItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/category\\\/corporativo\\\/#listItem\",\"name\":\"Corporativo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/category\\\/corporativo\\\/#listItem\",\"position\":2,\"name\":\"Corporativo\",\"item\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/category\\\/corporativo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/nuevos-horarios-del-club\\\/#listItem\",\"name\":\"Nuevos horarios del Club\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en#listItem\",\"name\":\"Hogar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/nuevos-horarios-del-club\\\/#listItem\",\"position\":3,\"name\":\"Nuevos horarios del Club\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/category\\\/corporativo\\\/#listItem\",\"name\":\"Corporativo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/#organization\",\"name\":\"El bosque golf\",\"description\":\"Club de Golf Valencia\",\"url\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/author\\\/elbosquec\\\/#author\",\"url\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/author\\\/elbosquec\\\/\",\"name\":\"elbosquec\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/nuevos-horarios-del-club\\\/#webpage\",\"url\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/nuevos-horarios-del-club\\\/\",\"name\":\"Nuevos horarios del Club | El bosque golf\",\"description\":\"Con el cambio de hora, hemos adaptado los horarios de apertura y cierre de las diferentes \\u00e1reas y servicios.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/nuevos-horarios-del-club\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/author\\\/elbosquec\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/author\\\/elbosquec\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elbosquegolf.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Nuevo-horario-copia.jpg\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/nuevos-horarios-del-club\\\/#mainImage\",\"width\":1080,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/nuevos-horarios-del-club\\\/#mainImage\"},\"datePublished\":\"2020-10-26T16:26:24+01:00\",\"dateModified\":\"2020-10-26T16:26:26+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/\",\"name\":\"El bosque\",\"description\":\"Club de Golf Valencia\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elbosquegolf.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Nuevos horarios del Club | El bosque golf","description":"Con el cambio de hora, hemos adaptado los horarios de apertura y cierre de las diferentes \u00e1reas y servicios.","canonical_url":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/#article","name":"Nuevos horarios del Club | El bosque golf","headline":"Nuevos horarios del Club","author":{"@id":"https:\/\/www.elbosquegolf.com\/en\/author\/elbosquec\/#author"},"publisher":{"@id":"https:\/\/www.elbosquegolf.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.elbosquegolf.com\/wp-content\/uploads\/2020\/10\/Nuevo-horario-copia.jpg","width":1080,"height":1080},"datePublished":"2020-10-26T16:26:24+01:00","dateModified":"2020-10-26T16:26:26+01:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/#webpage"},"isPartOf":{"@id":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/#webpage"},"articleSection":"Corporativo, club, horarios"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en#listItem","position":1,"name":"Hogar","item":"https:\/\/www.elbosquegolf.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en\/category\/corporativo\/#listItem","name":"Corporativo"}},{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en\/category\/corporativo\/#listItem","position":2,"name":"Corporativo","item":"https:\/\/www.elbosquegolf.com\/en\/category\/corporativo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/#listItem","name":"Nuevos horarios del Club"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en#listItem","name":"Hogar"}},{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/#listItem","position":3,"name":"Nuevos horarios del Club","previousItem":{"@type":"ListItem","@id":"https:\/\/www.elbosquegolf.com\/en\/category\/corporativo\/#listItem","name":"Corporativo"}}]},{"@type":"Organization","@id":"https:\/\/www.elbosquegolf.com\/en\/#organization","name":"El bosque golf","description":"Club de Golf Valencia","url":"https:\/\/www.elbosquegolf.com\/en\/"},{"@type":"Person","@id":"https:\/\/www.elbosquegolf.com\/en\/author\/elbosquec\/#author","url":"https:\/\/www.elbosquegolf.com\/en\/author\/elbosquec\/","name":"elbosquec"},{"@type":"WebPage","@id":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/#webpage","url":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/","name":"Nuevos horarios del Club | El bosque golf","description":"Con el cambio de hora, hemos adaptado los horarios de apertura y cierre de las diferentes \u00e1reas y servicios.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.elbosquegolf.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/#breadcrumblist"},"author":{"@id":"https:\/\/www.elbosquegolf.com\/en\/author\/elbosquec\/#author"},"creator":{"@id":"https:\/\/www.elbosquegolf.com\/en\/author\/elbosquec\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.elbosquegolf.com\/wp-content\/uploads\/2020\/10\/Nuevo-horario-copia.jpg","@id":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/#mainImage","width":1080,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/#mainImage"},"datePublished":"2020-10-26T16:26:24+01:00","dateModified":"2020-10-26T16:26:26+01:00"},{"@type":"WebSite","@id":"https:\/\/www.elbosquegolf.com\/en\/#website","url":"https:\/\/www.elbosquegolf.com\/en\/","name":"El bosque","description":"Club de Golf Valencia","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.elbosquegolf.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"El bosque golf | Club de Golf Valencia","og:type":"article","og:title":"Nuevos horarios del Club | El bosque golf","og:description":"Con el cambio de hora, hemos adaptado los horarios de apertura y cierre de las diferentes \u00e1reas y servicios.","og:url":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/","article:published_time":"2020-10-26T15:26:24+00:00","article:modified_time":"2020-10-26T15:26:26+00:00","twitter:card":"summary_large_image","twitter:title":"Nuevos horarios del Club | El bosque golf","twitter:description":"Con el cambio de hora, hemos adaptado los horarios de apertura y cierre de las diferentes \u00e1reas y servicios."},"aioseo_meta_data":{"post_id":"25568","title":"Nuevos horarios del Club | #site_title","description":"Con el cambio de hora, hemos adaptado los horarios de apertura y cierre de las diferentes \u00e1reas y servicios.","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-12-23 18:28:38","updated":"2025-06-04 07:48:53","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elbosquegolf.com\/en\" title=\"Hogar\">Hogar<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elbosquegolf.com\/en\/category\/corporativo\/\" title=\"Corporativo\">Corporativo<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNuevos horarios del Club\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Hogar","link":"https:\/\/www.elbosquegolf.com\/en"},{"label":"Corporativo","link":"https:\/\/www.elbosquegolf.com\/en\/category\/corporativo\/"},{"label":"Nuevos horarios del Club","link":"https:\/\/www.elbosquegolf.com\/en\/nuevos-horarios-del-club\/"}],"_links":{"self":[{"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/posts\/25568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/comments?post=25568"}],"version-history":[{"count":0,"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/posts\/25568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/media\/25569"}],"wp:attachment":[{"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/media?parent=25568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/categories?post=25568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elbosquegolf.com\/en\/wp-json\/wp\/v2\/tags?post=25568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}